{"id":4640,"date":"2017-10-18T20:53:14","date_gmt":"2017-10-18T19:53:14","guid":{"rendered":"http:\/\/indainiciativas.com\/?p=4640"},"modified":"2024-03-18T10:57:34","modified_gmt":"2024-03-18T09:57:34","slug":"congreso-internacional-sobre-migracions","status":"publish","type":"post","link":"https:\/\/indainiciativas.com\/en\/congreso-internacional-sobre-migracions\/","title":{"rendered":"Congreso internacional sobre migraci\u00f3ns"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Os pasados <strong>4, 5 e 6 de outubro,<\/strong> a Casa da Cultura de Vimianzo acolleu con grande \u00e9xito o congreso internacional <strong>\u00abEmigraci\u00f3n e inmigraci\u00f3n por raz\u00f3ns laborais no rural da Uni\u00f3n Europea\u00bb.<\/strong> O congreso, organizado polo <strong>Vimianzo Town Council<\/strong> en colaboraci\u00f3n con<strong> Inda Iniciativas SL, Urzad Miasta Kostrzyn nad Odra<\/strong> (Polonia), <strong>Comunidade Intermunicipal do Alto Alentejo<\/strong> (Portugal), <strong>Newry, Mourne and Down District Council<\/strong> (Irlanda do Norte, Reino Unido), <strong>Comune di Petrosino<\/strong> (Italia) e <strong>Obec Zemplinske H\u00e1mre<\/strong> (Eslovaquia), contou coa supervisi\u00f3n do comit\u00e9 cient\u00edfico conformado polo <strong><a href=\"http:\/\/esomi.es\/index.php\/es\/\">ESOMI<\/a><\/strong> (Equipo de Sociolox\u00eda das Migraci\u00f3ns Internacionais), pertencente \u00e1 Facultade de Sociolox\u00eda da Universidade da Coru\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este congreso internacional enm\u00e1rcase no proxecto europeo <strong><a href=\"http:\/\/www.vimianzo.gal\/ern4mob\/\">\u00abERN4mob \u2013 European Rural Network for Job Mobility\u00bb,<\/a><\/strong> pertencente ao programa <strong>Europa cos Cidad\u00e1ns 2014-2020,<\/strong> que ten como obxectivo principal conectar as persoas de diferentes pa\u00edses da Uni\u00f3n Europea e m\u00e1is al\u00e1 da Uni\u00f3n que viven conxuntamente nas mesmas comunidades locais, para sensibilizar acerca dos seus valores e necesidades com\u00fans, as\u00ed como para promover o empoderamento das s\u00faas diferenzas sociais e multiculturais, a trav\u00e9s da creaci\u00f3n dunha rede de municipios rurais europeos para a mobilidade laboral que funcione a favor da integraci\u00f3n social e laboral da cidadan\u00eda, co fin de lograr un crecemento intelixente, sustentable e integrador da Europa rural 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo das tres xornadas, suced\u00e9ronse relatorios, paneis expositivos e paneis de experiencias, relacionados todos cos movementos migratorios en Europa, e non faltaron perspectivas e testemu\u00f1os da emigraci\u00f3n galega. As\u00ed, xunto a paneis como <strong>\u00abA mobilidade en Europa na actualidade\u00bb<\/strong> ou <strong>\u00abA acci\u00f3n da sociedade diante da migraci\u00f3n\u00bb<\/strong> tam\u00e9n houbo lugar para as experiencias de emigrantes retornados de Canad\u00e1, Su\u00edza ou o Reino Unido. O congreso acolleu ademais a presentaci\u00f3n de comunicaci\u00f3ns cient\u00edficas en tres mesas (sobre emigraci\u00f3n galega, inmigraci\u00f3n en Galicia e retos da Europa rural ante as migraci\u00f3ns, respectivamente), e presentou os resultados e as perspectivas de futuro para o proxecto <strong>ERN4mob.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/indainiciativas.com\/wp-content\/uploads\/2017\/10\/ERN4mobCongreso2017-def.pdf\">Programa do congreso internacional (PDF, 1,12 MB)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.lavozdegalicia.es\/noticia\/carballo\/2017\/10\/07\/emigrantes-siglo-xxi-empleos-iguales-abuelos\/0003_201710C7C7991.htm\">Unha das noticias do congreso internacional en <em>La Voz de Galicia<\/em><\/a><\/li>\n\n\n\n<li><a href=\"http:\/\/www.elcorreogallego.es\/area-de-compostela\/ecg\/vimianzo-evalua-fenomeno-migraciones-europa\/idEdicion-2017-10-05\/idNoticia-1076050\/\">Noticia do congreso en <em>El Correo Gallego<\/em><\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Os pasados 4, 5 e 6 de outubro, a Casa  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":4646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3,4],"tags":[],"class_list":["post-4640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-programas-europeos","category-xestion-sociocultural"],"_links":{"self":[{"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/posts\/4640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/comments?post=4640"}],"version-history":[{"count":1,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/posts\/4640\/revisions"}],"predecessor-version":[{"id":5858,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/posts\/4640\/revisions\/5858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/media\/4646"}],"wp:attachment":[{"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/media?parent=4640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/categories?post=4640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/tags?post=4640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}