{"id":5964,"date":"2025-02-28T12:28:16","date_gmt":"2025-02-28T11:28:16","guid":{"rendered":"https:\/\/indainiciativas.com\/?p=5964"},"modified":"2025-02-28T12:30:47","modified_gmt":"2025-02-28T11:30:47","slug":"reunion-de-puesta-en-marcha-del-proyecto-digecp","status":"publish","type":"post","link":"https:\/\/indainiciativas.com\/en\/reunion-de-puesta-en-marcha-del-proyecto-digecp\/","title":{"rendered":"Reuni\u00f3n de puesta en marcha del proyecto DIGECP"},"content":{"rendered":"<p><strong>El Distintivo por la Igualdad de G\u00e9nero servir\u00e1 para certificar el compromiso de los municipios con las pol\u00edticas de igualdad<\/strong><\/p>\n\n\n\n<p>El pasado d\u00eda 21 de febrero tuvo lugar en A Coru\u00f1a la 1.\u00aa Reuni\u00f3n de Coordinaci\u00f3n <strong>(Reuni\u00f3n de Puesta en Marcha)<\/strong> del proyecto <strong>DIGECP<\/strong> (Distintivo por la Igualdad de G\u00e9nero en Pueblos y Ciudades), que llevan adelante la asociaci\u00f3n <strong>ForGender Seal<\/strong> (Barcelona) y la empresa <strong>INDA Iniciativas, S.\u00a0L.<\/strong> (A Coru\u00f1a) con la cofinanciaci\u00f3n de la <strong>Uni\u00f3n Europea.<\/strong><\/p>\n\n\n\n<p>El proyecto <strong>DIGECP<\/strong> propone a los municipios una norma de certificaci\u00f3n a favor de la igualdad de g\u00e9nero dise\u00f1ada de acuerdo con las competencias locales, la normativa estatal y los mandatos y tratados internacionales en relaci\u00f3n con los derechos humanos de las mujeres, el desarrollo humano, las ciudades y el cambio clim\u00e1tico. Mediante un proceso de evaluaci\u00f3n y certificaci\u00f3n, un municipio puede obtener el <strong>Distintivo por la Igualdad de G\u00e9nero.<\/strong><\/p>\n\n\n\n<p>El principal objetivo del <strong>Distintivo<\/strong> es ayudar a los municipios a integrar la perspectiva de g\u00e9nero con un enfoque transversal e interseccional tanto a nivel organizativo como en todas sus pol\u00edticas p\u00fablicas y actuaciones, de forma que se puedan hacer efectivos los derechos de las mujeres y se beneficie a toda la poblaci\u00f3n del municipio. De acuerdo con sus responsables, \u00abel proceso de certificaci\u00f3n del <strong>DIGECP<\/strong> fortalece la imagen del ayuntamiento como una administraci\u00f3n comprometida con los derechos de las mujeres\u00bb.<\/p>\n\n\n\n<p>Para este fin, los dos socios de este proyecto lanzar\u00e1n diversas acciones para informar y sensibilizar a los ayuntamientos sobre la importancia de la certificaci\u00f3n para incorporar la perspectiva de g\u00e9nero en las pol\u00edticas municipales y en especial sobre el valor del trabajo de cuidado, los estereotipos que perpet\u00faan la divisi\u00f3n tradicional del trabajo, y la promoci\u00f3n de pr\u00e1cticas que fomentan el equilibrio entre la vida laboral y personal de hombres y mujeres. Uno de los objetivos es crear una <strong>Red de municipalidades por la igualdad de g\u00e9nero y la corresponsabilidad en los usos del tiempo<\/strong> con los ayuntamientos que se sumen a la iniciativa.<\/p>\n\n\n\n<p>En esta primera reuni\u00f3n, se revisaron los paquetes de trabajo (tareas, roles y calendario) y la planificaci\u00f3n de los pr\u00f3ximos pasos del proyecto. Entre esos pr\u00f3ximos pasos se encuentran una campa\u00f1a de sensibilizaci\u00f3n y la realizaci\u00f3n de diversas sesiones informativas sobre el Distintivo, as\u00ed como dos ediciones del <strong>F\u00f3rum de Municipios Certificados,<\/strong> consistentes en jornadas de intercambio de buenas pr\u00e1cticas en igualdad de g\u00e9nero en la gesti\u00f3n municipal, acompa\u00f1adas de conferencias y mesas redondas con personas expertas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-1024x768.jpg\" alt=\"\" class=\"wp-image-5966\" srcset=\"https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-16x12.jpg 16w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-66x50.jpg 66w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-177x133.jpg 177w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-200x150.jpg 200w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-300x225.jpg 300w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-320x240.jpg 320w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-400x300.jpg 400w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-460x345.jpg 460w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-540x405.jpg 540w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-600x450.jpg 600w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-669x502.jpg 669w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-700x525.jpg 700w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-768x576.jpg 768w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-800x600.jpg 800w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-940x705.jpg 940w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-1024x768.jpg 1024w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-1200x900.jpg 1200w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP-1536x1152.jpg 1536w, https:\/\/indainiciativas.com\/wp-content\/uploads\/2025\/02\/reunion_inicio-DIGECP.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>El Distintivo por la Igualdad de G\u00e9nero servir\u00e1 para certificar  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":5965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-5964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-programas-europeos"],"_links":{"self":[{"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/posts\/5964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/comments?post=5964"}],"version-history":[{"count":2,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/posts\/5964\/revisions"}],"predecessor-version":[{"id":5968,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/posts\/5964\/revisions\/5968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/media\/5965"}],"wp:attachment":[{"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/media?parent=5964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/categories?post=5964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indainiciativas.com\/en\/wp-json\/wp\/v2\/tags?post=5964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}