{"id":4411,"date":"2014-03-05T12:28:00","date_gmt":"2014-03-05T11:28:00","guid":{"rendered":"http:\/\/indainiciativas.com\/?p=4411"},"modified":"2024-03-14T15:21:57","modified_gmt":"2024-03-14T14:21:57","slug":"o-programa-erasmus-moito-mais-que-intercambios-universitarios","status":"publish","type":"post","link":"https:\/\/indainiciativas.com\/es\/o-programa-erasmus-moito-mais-que-intercambios-universitarios\/","title":{"rendered":"O programa Erasmus+, moito m\u00e1is que intercambios universitarios"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O programa <a href=\"http:\/\/ec.europa.eu\/programmes\/erasmus-plus\/index_es.htm\"><b>Erasmus+,<\/b><\/a> convocado pola Uni\u00f3n Europea o pasado mes de decembro, servir\u00e1 para acceder a axudas, pr\u00e1cticas laborais e actividades de voluntariado nos pr\u00f3ximos sete anos no \u00e1mbito da educaci\u00f3n, a formaci\u00f3n, a xuventude e o deporte. O orzamento ata 2020 \u00e9 de 14&nbsp;700 mill\u00f3ns de euros, dos cales o 60&nbsp;% se destinar\u00e1 a programas de mobilidade; un 43&nbsp;% est\u00e1 reservado \u00e1 educaci\u00f3n superior. Para 2014 o presuposto \u00e9 de 1507,3 mill\u00f3ns de euros.<br><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><b>Erasmus+<\/b> \u00e9 un programa de acci\u00f3n que abarcar\u00e1 os \u00e1mbitos da educaci\u00f3n e a formaci\u00f3n a todos os niveis, cunha perspectiva de aprendizaxe permanente, inclu\u00edda a educaci\u00f3n escolar <b>(Comenius<\/b><b>),<\/b> a educaci\u00f3n superior <b>(Erasmus),<\/b> a educaci\u00f3n superior internacional <b>(Erasmus Mundus),<\/b> a educaci\u00f3n e a formaci\u00f3n profesionais <b>(Leonardo da Vinci),<\/b> a aprendizaxe de adultos <b>(Grundtvig)<\/b> e os estudos europeos <b>(Jean Monnet).<\/b> Ademais, outros \u00e1mbitos ser\u00e1n a xuventude <b>(Xuventude en Acci\u00f3n),<\/b> en particular a aprendizaxe non formal e informal, e o <b>deporte,<\/b> nomeadamente o de base. \u00c1 parte da mobilidade estudantil, <b>Erasmus+<\/b> busca tam\u00e9n o intercambio entre organismos e instituci\u00f3ns, profesores e responsables universitarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este programa abrangue as acci\u00f3ns clave <b>\u00abMobilidade das persoas por motivos de aprendizaxe\u00bb<\/b> (mobilidade no \u00e1mbito da educaci\u00f3n, a formaci\u00f3n e a xuventude; titulaci\u00f3ns de mestrado conxuntas e eventos a grande escala do Servizo Voluntario Europeo), <b>\u00abCooperaci\u00f3n para a innovaci\u00f3n e o intercambio de boas pr\u00e1cticas\u00bb<\/b> (asociaci\u00f3ns estrat\u00e9xicas no \u00e1mbito da educaci\u00f3n, a formaci\u00f3n e a xuventude, alianzas para o co\u00f1ecemento, alianzas para as competencias sectoriais e reforzo de capacidades no \u00e1mbito da xuventude) e <b>\u00abApoio \u00e1 reforma das pol\u00edticas\u00bb<\/b> (di\u00e1logo estruturado entre os os mozos e mozas e os responsables da toma de decisi\u00f3ns no \u00e1mbito da xuventude). Ademais, est\u00e1n as acci\u00f3ns <b>Jean Monnet<\/b> (c\u00e1tedras, m\u00f3dulos, centros de excelencia, redes, proxectos, apoio a instituci\u00f3ns e asociaci\u00f3ns) e mais as <b>actividades deportivas<\/b> (asociaci\u00f3ns en colaboraci\u00f3n no \u00e1mbito do deporte, e acontecementos deportivos europeos sen \u00e1nimo de lucro).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pode solicitar financiamento con cargo ao programa <b>Erasmus+<\/b> calquera entidade p\u00fablica ou privada que traballe no \u00e1mbito da educaci\u00f3n, a formaci\u00f3n, a xuventude e o deporte; al\u00e9n diso, algunhas acci\u00f3ns est\u00e1n abertas tam\u00e9n a organizaci\u00f3ns do \u00e1mbito laboral e social. Ademais, os grupos de mozos e mozas que traballen no sector da xuventude \u2014a\u00ednda que non necesariamente no marco dunha organizaci\u00f3n xuvenil: por exemplo, grupos informais\u2014, poder\u00e1n solicitar financiamento para mobilidade por motivos de aprendizaxe de mozos, estudantes ou traballadores, as\u00ed como para asociaci\u00f3ns estrat\u00e9xicas no \u00e1mbito da xuventude. Non obstante, hai que ter en conta que a elixibilidade dos beneficiarios var\u00eda en funci\u00f3n de cada acci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As datas l\u00edmite para a presentaci\u00f3n de proxectos son diferentes para cada tipo de acci\u00f3n; a m\u00e1is pr\u00f3xima (mobilidade das persoas no \u00e1mbito da educaci\u00f3n, a formaci\u00f3n e a xuventude, conxuntamente) \u00e9 o pr\u00f3ximo 17 de marzo de 2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><b>INDA Iniciativas<\/b> est\u00e1 xa a traballar en propostas, e ofrece a s\u00faa experiencia en asesoramento e xesti\u00f3n integral en calquera das acci\u00f3ns. Para maior informaci\u00f3n sobre calquera das acci\u00f3ns do programa, non dubide en contactar connosco.<\/p>","protected":false},"excerpt":{"rendered":"<p>O programa Erasmus+, convocado pola Uni\u00f3n Europea o pasado mes  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":4419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-4411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-programas-europeos"],"_links":{"self":[{"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/posts\/4411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/comments?post=4411"}],"version-history":[{"count":2,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/posts\/4411\/revisions"}],"predecessor-version":[{"id":5692,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/posts\/4411\/revisions\/5692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/media\/4419"}],"wp:attachment":[{"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/media?parent=4411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/categories?post=4411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/tags?post=4411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}