{"id":4619,"date":"2017-01-26T16:18:35","date_gmt":"2017-01-26T15:18:35","guid":{"rendered":"http:\/\/indainiciativas.com\/?p=4619"},"modified":"2024-03-18T11:01:01","modified_gmt":"2024-03-18T10:01:01","slug":"en-marcha-o-proxecto-agrosmartcoop","status":"publish","type":"post","link":"https:\/\/indainiciativas.com\/es\/en-marcha-o-proxecto-agrosmartcoop\/","title":{"rendered":"En marcha o proxecto AGROSMARTcoop"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O proxecto <strong><a href=\"http:\/\/www.agrosmartcoop.eu\">AGROSMARTcoop,<\/a><\/strong> \u00abEspazo para a integraci\u00f3n, a competitividade e o crecemento econ\u00f3mico intelixente das cooperativas agroalimentarias do espazo rural SUDOE\u00bb, abrangue <strong>seis rexi\u00f3ns do espazo SUDOE<\/strong> (Galicia, Castilla-La Mancha, Pa\u00eds Vasco e Extremadura en Espa\u00f1a; Aquitaine en Francia, e Norte de Portugal en Portugal) e busca paliar as desvantaxes das s\u00faas zonas rurais, as\u00ed como favorecer o desenvolvemento e a cohesi\u00f3n econ\u00f3mica, a trav\u00e9s da xeraci\u00f3n de capacidades e a busca de soluci\u00f3ns transnacionais m\u00e1is eficientes e efectivas para apoiar as cooperativas agroalimentarias nas s\u00faas necesidades espec\u00edficas e mellorar a s\u00faa competitividade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proxecto forma parte do programa <strong><a href=\"http:\/\/www.interreg-sudoe.eu\/inicio\">Interreg SUDOE 2014-2020<\/a><\/strong> (1.\u00aa convocatoria 2015), dentro da prioridade \u00abFomentar a competitividade e a internacionalizaci\u00f3n das pemes do Suroeste europeo\u00bb; tivo como data de inicio o 1 de xullo de 2016, e a s\u00faa data prevista de finalizaci\u00f3n \u00e9 o 30 de xu\u00f1o de 2018. Conta cun orzamento total de <strong>1.295.000,00 euros,<\/strong> cunha axuda FEDER de 971.250,00 euros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>INDA Iniciativas<\/strong> colaborou co beneficiario principal, <strong><a href=\"http:\/\/agaca.coop\">AGACA,<\/a><\/strong> na definici\u00f3n da idea de proxecto, na busca de socios e a conformaci\u00f3n do consorcio transnacional, e no desenvolvemento do plan de traballo e do orzamento, as\u00ed como na redacci\u00f3n dos formularios nas fases 1 e 2 da tramitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O obxectivo principal do proxecto \u00e9 crear un espazo de promoci\u00f3n, interconexi\u00f3n e interacci\u00f3n intelixente dotado de estruturas, ferramentas e servizos avanzados de apoio \u00e1s cooperativas agroalimentarias do SUDOE para mellorar na innovaci\u00f3n tecnol\u00f3xica, de xesti\u00f3n e de comercializaci\u00f3n a trav\u00e9s do fomento do co\u00f1ecemento, as boas pr\u00e1cticas e a intercooperaci\u00f3n.<br>Os principais produtos do proxecto beneficiar\u00e1n principalmente as cooperativas agroalimentarias do espazo SUDOE. Entre eles est\u00e1n os Grupos Operativos Transnacionais para a innovaci\u00f3n sustentable e comercializaci\u00f3n e m\u00e1rketing intelixente, o Plan estrat\u00e9xico conxunto para a competitividade das cooperativas agroalimentarias do espazo SUDOE, a Plataforma virtual para a intercooperaci\u00f3n e fomento de pr\u00e1cticas innovadoras ou o Laboratorio virtual (AgroLAB). Ademais disto, haber\u00e1 asesor\u00edas t\u00e9cnicas \u00e1 innovaci\u00f3n tecnol\u00f3xica sustentable e \u00e1 comercializaci\u00f3n intelixente, conformarase unha Comunidade de cooperativas agroalimentarias para a intercooperaci\u00f3n, e porase en marcha unha campa\u00f1a de divulgaci\u00f3n e promoci\u00f3n de pr\u00e1cticas innovadoras entre as cooperativas agroalimentarias, as\u00ed como un programa de formaci\u00f3n e capacitaci\u00f3n para a innovaci\u00f3n sustentable e comercializaci\u00f3n intelixente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un aspecto innovador do proxecto \u00e9 abordar a innovaci\u00f3n desde a intercooperaci\u00f3n, como recurso clave para o investimento na posta en marcha de novas t\u00e9cnicas e tecnolox\u00edas de innovaci\u00f3n sustentable e m\u00e1rketing; ademais, introduce un concepto novo, a comercializaci\u00f3n intelixente, que consiste en aproveitar o potencial das cooperativas (a calidade e o car\u00e1cter end\u00f3xeno dos seus produtos) e ali\u00f1alo coa innovaci\u00f3n, a ciencia e a tecnolox\u00eda.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"http:\/\/www.agrosmartcoop.eu\">M\u00e1is informaci\u00f3n, na web espec\u00edfica do proxecto.<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>O proxecto AGROSMARTcoop, \u00abEspazo para a integraci\u00f3n, a competitividade e  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":4620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-4619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-programas-europeos"],"_links":{"self":[{"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/posts\/4619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/comments?post=4619"}],"version-history":[{"count":2,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/posts\/4619\/revisions"}],"predecessor-version":[{"id":5863,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/posts\/4619\/revisions\/5863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/media\/4620"}],"wp:attachment":[{"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/media?parent=4619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/categories?post=4619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indainiciativas.com\/es\/wp-json\/wp\/v2\/tags?post=4619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}